{"id":187657,"date":"2026-06-29T16:37:50","date_gmt":"2026-06-29T19:37:50","guid":{"rendered":"https:\/\/www.itsitio.com\/ar\/?p=187657"},"modified":"2026-06-29T17:25:06","modified_gmt":"2026-06-29T20:25:06","slug":"el-rol-de-la-ia-en-la-creatividad-publicitaria-segun-purga-studio","status":"publish","type":"post","link":"https:\/\/www.itsitio.com\/ar\/inteligencia-artificial\/el-rol-de-la-ia-en-la-creatividad-publicitaria-segun-purga-studio\/","title":{"rendered":"El rol de la IA en la creatividad publicitaria seg\u00fan Purga Studio"},"content":{"rendered":"<p class=\"isSelectedEnd\">La irrupci\u00f3n de la inteligencia artificial en la industria audiovisual abri\u00f3 un debate que atraviesa a agencias, productoras y estudios creativos. Mientras algunos ven en estas herramientas una amenaza para los procesos tradicionales, otros las consideran una oportunidad para ampliar las posibilidades narrativas y visuales. En ese escenario naci\u00f3 <strong>Purga Studio<\/strong>, un estudio creativo argentino fundado en 2025 por <strong>Sebasti\u00e1n Aspani, Manuel Montes de Oca y Bautista Vidal<\/strong> que busca integrar la inteligencia artificial como parte del proceso de producci\u00f3n sin perder de vista que el valor diferencial contin\u00faa estando en la direcci\u00f3n creativa.<\/p>\n<p class=\"isSelectedEnd\"><strong>Mart\u00edn Montes de Oca, Director AI de Purga Studio<\/strong>, explic\u00f3 a ITSitio que el origen del estudio estuvo ligado a una convicci\u00f3n compartida entre sus fundadores: eliminar muchas de las limitaciones que hist\u00f3ricamente condicionaron el desarrollo de proyectos audiovisuales. <strong>El objetivo no era reemplazar la creatividad humana, sino permitir que las ideas pudieran desarrollarse sin quedar restringidas<\/strong> por cuestiones de presupuesto o complejidad t\u00e9cnica.<\/p>\n<p>En 2026, Purga alcanz\u00f3 uno de los hitos m\u00e1s importantes de su trayectoria al convertirse en la \u00fanica productora especializada en inteligencia artificial de Iberoam\u00e9rica premiada en la categor\u00eda <strong data-start=\"893\" data-end=\"901\">Film<\/strong> del <strong data-start=\"906\" data-end=\"936\">Festival Cannes Lions 2026<\/strong>, considerado el reconocimiento m\u00e1s importante de la industria creativa a nivel global. Adem\u00e1s del galard\u00f3n, el estudio obtuvo cinco shortlists en las categor\u00edas <strong data-start=\"1098\" data-end=\"1170\">Film Craft, Digital Craft, B2B, Guion y Video e Imagen en Movimiento<\/strong>.<\/p>\n<h2><span style=\"color: #333399;\">El origen de Purga y el potencial de la inteligencia artificial<\/span><\/h2>\n<p class=\"isSelectedEnd\">En ese camino, record\u00f3 que uno de los primeros proyectos que les permiti\u00f3 comprobar el potencial de estas herramientas fue una campa\u00f1a realizada para<strong> TyC Sports<\/strong>.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;El primer proyecto que demostr\u00f3 la utilidad de la IA fue La Impresora de los Lunes de TyC Sports. Cuando lo empezamos a desarrollar pudimos tomar una idea pensada para un escenario local y llevarla a algo con escala internacional. Lo que m\u00e1s nos entusiasma de la herramienta es sacar ideas del caj\u00f3n y otras hacerlas crecer hasta donde realmente pueden llegar&#8221;.<\/em><\/p>\n<p class=\"isSelectedEnd\">Sin embargo, aclar\u00f3 que el nacimiento de Purga no estuvo asociado exclusivamente a ese trabajo puntual, sino a un proceso de exploraci\u00f3n mucho m\u00e1s amplio que comenz\u00f3 cuando la inteligencia artificial todav\u00eda daba sus primeros pasos.<\/p>\n<p class=\"isSelectedEnd\"><em><span style=\"color: #333333;\">&#8220;Por curiosidad empezamos a experimentar con herramientas de IA cuando todav\u00eda estaban en sus primeros pasos y vimos un potencial grande. Hoy vemos lo mismo, la IA mejor\u00f3 mucho pero todav\u00eda tiene que seguir mejorando en muchos aspectos&#8221;.<\/span><\/em><\/p>\n<p class=\"isSelectedEnd\">Seg\u00fan explic\u00f3, las nuevas herramientas permiten resolver muchas de las limitaciones t\u00e9cnicas y de escala que tradicionalmente condicionaban una producci\u00f3n audiovisual, aunque al mismo tiempo introducen nuevos desaf\u00edos que obligan a repensar la manera de trabajar.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;Resuelve muchas de las limitaciones t\u00e9cnicas o de escala de una campa\u00f1a o producci\u00f3n, abre posibilidades que antes no exist\u00edan, pero tambi\u00e9n trae otras nuevas. Por eso analizamos cada gui\u00f3n de manera individual para entender qu\u00e9 posibilidades habilita la tecnolog\u00eda, cu\u00e1les son sus restricciones y c\u00f3mo utilizarla al servicio de la historia que queremos contar. Tenemos claro que las limitaciones t\u00e9cnicas van a ir desapareciendo hasta que solo quede lo importante: la idea creativa y lo que quer\u00e9s contar&#8221;.<\/em><\/p>\n<figure id=\"attachment_187660\" aria-describedby=\"caption-attachment-187660\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-187660 size-full\" src=\"https:\/\/www.itsitio.com\/ar\/wp-content\/uploads\/sites\/2\/2026\/06\/Lideres-de-Purga-e1782761116707.jpeg\" alt=\"Bautista Vidal, Manuel Montes de Oca y Sebasti\u00e1n Aspani fundadores de Purga Studio.\" width=\"1200\" height=\"900\" \/><figcaption id=\"caption-attachment-187660\" class=\"wp-caption-text\">Bautista Vidal, Manuel Montes de Oca y Sebasti\u00e1n Aspani fundadores de Purga Studio.<\/figcaption><\/figure>\n<h2><span style=\"color: #333399;\">Un nuevo paradigma para pensar las producciones<\/span><\/h2>\n<p class=\"isSelectedEnd\">Uno de los conceptos que m\u00e1s identifica a Purga es la posibilidad de pensar proyectos sin que el presupuesto determine desde el comienzo el alcance de una idea. Montes de Oca explic\u00f3 que la inteligencia artificial modific\u00f3 parte de esa ecuaci\u00f3n al eliminar determinadas barreras econ\u00f3micas relacionadas con la escala de producci\u00f3n.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;S\u00ed, desaparecen ciertas barreras que antes condicionaban decisiones creativas, dependiendo de las variables en la escala de producci\u00f3n. Antes, elegir un escenario m\u00e1s ambicioso o una propuesta visual m\u00e1s elaborada ten\u00eda un costo directo. Hoy esa decisi\u00f3n no te sale m\u00e1s caro. Pero eso no significa que todo sea posible, hay que entender las limitaciones propias de la IA. Por eso el proceso arranca con un an\u00e1lisis del gui\u00f3n, donde identificamos cu\u00e1les son los desaf\u00edos y qu\u00e9 caminos existen para resolverlos&#8221;.<\/em><\/p>\n<h2><span style=\"color: #333399;\">La direcci\u00f3n creativa como principal diferencial<\/span><\/h2>\n<p class=\"isSelectedEnd\">Para el director de IA del estudio, el verdadero diferencial de Purga no pasa \u00fanicamente por el uso de herramientas tecnol\u00f3gicas, sino por la experiencia profesional del equipo que las utiliza.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;Creo que la diferencia tiene que ver con qui\u00e9nes estamos detr\u00e1s. Todos estudiamos y trabajamos en publicidad y cine, en direcci\u00f3n, en fotograf\u00eda, en producci\u00f3n y en post. En Purga seguimos pensando desde la narrativa, el ritmo, la puesta en escena, la construcci\u00f3n de una identidad visual&#8221;.<\/em><\/p>\n<p class=\"isSelectedEnd\">A partir de esa visi\u00f3n, explic\u00f3 que <strong>el estudio evita definir sus trabajos simplemente como contenido generado mediante inteligencia artificial.<\/strong><\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;La distinci\u00f3n m\u00e1s importante es que la industria habla de contenido generado por IA y nosotros hablamos de proyectos dirigidos con herramientas de IA. La mirada y el criterio nos parecen lo m\u00e1s importante, independientemente del recurso que uses. Hay pel\u00edculas con millones de d\u00f3lares que fracasan y pel\u00edculas de bajo presupuesto que son espectaculares. La diferencia siempre es qui\u00e9n est\u00e1 detr\u00e1s y c\u00f3mo usa lo que tiene. La IA no deja de ser una herramienta. Existe la idea falsa de que apret\u00e1s un bot\u00f3n y sale el comercial, pero hay muchas horas de trabajo, esfuerzo y criterio en cada paso del proceso&#8221;.<\/em><\/p>\n<h2><span style=\"color: #333399;\">La creatividad humana sigue marcando el rumbo<\/span><\/h2>\n<p class=\"isSelectedEnd\">La conversaci\u00f3n sobre la p\u00e9rdida de identidad autoral es otro de los temas que aparecen con frecuencia cuando se habla de inteligencia artificial aplicada a la creatividad.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;La curiosidad, las inquietudes y las decisiones siguen siendo humanas. Si no sab\u00e9s bien a d\u00f3nde quer\u00e9s llegar termin\u00e1s con ideas muy gen\u00e9ricas y vac\u00edas. Lo que hay que explorar es qu\u00e9 mueve a cada uno. Como ya pasaba con cualquier proyecto de alg\u00fan director, directora o artista, no es algo nuevo lo que estoy diciendo, pero creo que parte de la misma falsa idea de que un bot\u00f3n hace todo&#8221;.<\/em><\/p>\n<p class=\"isSelectedEnd\">Ese concepto fue precisamente el eje de <strong>&#8220;Lorem Ipsum&#8221;, la campa\u00f1a desarrollada junto a GUT M\u00e9xico City e integrada por las piezas Mafia, Samurai y Western. <\/strong>Concebida como una declaraci\u00f3n de principios, la campa\u00f1a propone una reflexi\u00f3n sobre el papel de la direcci\u00f3n creativa en una industria atravesada por la inteligencia artificial. La pieza sostiene que, aunque la tecnolog\u00eda permite producir im\u00e1genes cada vez m\u00e1s sofisticadas, el verdadero diferencial contin\u00faa estando en la idea, la narrativa y la mirada humana detr\u00e1s de cada proyecto, un concepto que tambi\u00e9n atraviesa la visi\u00f3n de Purga Studio sobre el futuro de la producci\u00f3n audiovisual.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;La idea detr\u00e1s del proyecto fue demostrar que, en un contexto donde la tecnolog\u00eda puede generar im\u00e1genes cada vez m\u00e1s sofisticadas, el verdadero diferencial sigue estando en la direcci\u00f3n creativa. La IA fue una herramienta clave para la producci\u00f3n, pero las decisiones sobre el tono, la est\u00e9tica, la narrativa y el significado de la pieza estuvieron guiadas por una visi\u00f3n humana&#8221;.<\/em><\/p>\n<figure id=\"attachment_184638\" aria-describedby=\"caption-attachment-184638\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-184638 size-full\" src=\"https:\/\/www.itsitio.com\/ar\/wp-content\/uploads\/sites\/2\/2026\/01\/Foto-3-e1769457984155.jpg\" alt=\"El estudio analiza cada proyecto de manera individual para definir c\u00f3mo integrar la inteligencia artificial seg\u00fan las necesidades de la historia.\" width=\"1200\" height=\"582\" srcset=\"https:\/\/www.itsitio.com\/ar\/wp-content\/uploads\/sites\/2\/2026\/01\/Foto-3-e1769457984155.jpg 1200w, https:\/\/www.itsitio.com\/ar\/wp-content\/uploads\/sites\/2\/2026\/01\/Foto-3-e1769457984155-300x146.jpg 300w, https:\/\/www.itsitio.com\/ar\/wp-content\/uploads\/sites\/2\/2026\/01\/Foto-3-e1769457984155-1024x497.jpg 1024w, https:\/\/www.itsitio.com\/ar\/wp-content\/uploads\/sites\/2\/2026\/01\/Foto-3-e1769457984155-768x372.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-184638\" class=\"wp-caption-text\">El estudio analiza cada proyecto de manera individual para definir c\u00f3mo integrar la inteligencia artificial seg\u00fan las necesidades de la historia.<\/figcaption><\/figure>\n<h2><span style=\"color: #333399;\">El desaf\u00edo pendiente: emocionar con IA<\/span><\/h2>\n<p class=\"isSelectedEnd\">Consultado sobre los aspectos de la inteligencia artificial que todav\u00eda considera subestimados por la industria, Montes de Oca apunt\u00f3 directamente a la capacidad emocional de estas tecnolog\u00edas.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;Lo que est\u00e1 subestimado es la capacidad de transmitir emociones, que es en definitiva lo m\u00e1s importante y tambi\u00e9n lo que m\u00e1s est\u00e1 en desarrollo. Falta demostrar que la IA puede comunicar emociones e ideas m\u00e1s complejas. Incluso historias m\u00e1s simples que, aunque te des cuenta de que es inteligencia artificial no importe. Ah\u00ed va a estar el salto real. A m\u00ed me gusta pensarlo como una animaci\u00f3n hiperrealista: el pacto con el espectador cambia, pero si la emoci\u00f3n est\u00e1, la t\u00e9cnica pasa a segundo plano&#8221;.<\/em><\/p>\n<h2><span style=\"color: #333399;\">C\u00f3mo evolucion\u00f3 la relaci\u00f3n con los clientes<\/span><\/h2>\n<p class=\"isSelectedEnd\">La evoluci\u00f3n del mercado tambi\u00e9n modific\u00f3 el tipo de conversaciones que mantienen con sus clientes.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;Al principio las conversaciones giraban alrededor de la tecnolog\u00eda, quer\u00edan saber qu\u00e9 herramientas us\u00e1bamos, c\u00f3mo funcionaban y qu\u00e9 garant\u00edas hab\u00eda sobre la calidad. Hoy cada vez m\u00e1s clientes se enfocan en los resultados y eso es una se\u00f1al de madurez del mercado&#8221;.<\/em><\/p>\n<p class=\"isSelectedEnd\">Seg\u00fan explic\u00f3, uno de los prejuicios m\u00e1s frecuentes consist\u00eda en asociar la inteligencia artificial con una p\u00e9rdida del control creativo.<\/p>\n<p class=\"isSelectedEnd\"><em>&#8220;El principal prejuicio que tuvimos que trabajar fue la asociaci\u00f3n entre IA y p\u00e9rdida de control creativo. Y pudimos demostrar en los distintos proyectos que fuimos encarando que la tecnolog\u00eda puede convivir con est\u00e1ndares altos de craft y con procesos de direcci\u00f3n rigurosos. Cuando un cliente entiende que la direcci\u00f3n creativa sigue estando en el centro, la conversaci\u00f3n se enfoca en las posibilidades que abre. Ese es el momento en que la colaboraci\u00f3n se vuelve realmente interesante&#8221;.<\/em><\/p>\n<h2><span style=\"color: #333399;\">La visi\u00f3n de Purga para los pr\u00f3ximos a\u00f1os<\/span><\/h2>\n<p class=\"isSelectedEnd\">Pensando en el futuro, el Director AI de Purga consider\u00f3 que la inteligencia artificial terminar\u00e1 integr\u00e1ndose de manera natural al ecosistema audiovisual.<\/p>\n<p><em>&#8220;Creemos que la IA va a integrarse a los procesos audiovisuales de la misma manera que lo hacen otras tecnolog\u00edas a lo largo de la historia de la industria: primero genera resistencia, despu\u00e9s se naturaliza y finalmente se vuelve invisible. Para ese momento los estudios que hayan construido un modelo de trabajo s\u00f3lido, con criterio creativo y direcci\u00f3n clara tendr\u00e1n una ventaja sobre los que s\u00f3lo adoptaron la tecnolog\u00eda sin saber para qu\u00e9. Queremos estar como referentes de una transformaci\u00f3n tecnol\u00f3gica, como un estudio que sabe combinar talento, lenguaje audiovisual y nuevas herramientas para producir trabajo ambicioso y visualmente s\u00f3lido. Porque la tecnolog\u00eda cambia, pero una buena idea no&#8221;.<\/em><\/p>\n<h3><span style=\"color: #333399;\">Leer m\u00e1s<\/span><\/h3>\n<ul>\n<li class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.itsitio.com\/ar\/inteligencia-artificial\/la-uba-regula-el-uso-de-la-inteligencia-artificial-e-implementa-un-sistema-pionero\/\">La UBA regula el uso de la Inteligencia artificial e implementa un sistema pionero<\/a><\/li>\n<li class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.itsitio.com\/ar\/inteligencia-artificial\/agustin-mendilaharzu-un-empleado-ia-es-una-persona-que-se-suma-a-tu-empresa-que-aprende-en-la-manera-en-la-cual-operan-y-ejecuta-igual-que-un-ser-humano\/\">Agust\u00edn Mendilaharzu: \u201cUn empleado IA es una persona que se suma a tu empresa, que aprende en la manera en la cual operan y ejecuta igual que un ser humano\u201d<\/a><\/li>\n<li class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.itsitio.com\/ar\/software\/la-transformacion-de-ricoh-argentina-del-papel-a-los-datos-la-ia-y-la-automatizacion\/\">La transformaci\u00f3n de Ricoh Argentina: del papel a los datos, la IA y la automatizaci\u00f3n<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mart\u00edn Montes de Oca, Director AI de Purga Studio, analiza c\u00f3mo la inteligencia artificial est\u00e1 transformando la producci\u00f3n audiovisual en publicidad y cine, y destaca el rol central de la direcci\u00f3n creativa frente al avance tecnol\u00f3gico. Desde la experiencia del estudio, explica c\u00f3mo cambian los procesos de trabajo, la relaci\u00f3n con los clientes y el futuro de la industria en la regi\u00f3n.<\/p>\n","protected":false},"author":229,"featured_media":187658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[65],"tags":[646,1166],"class_list":["post-187657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inteligencia-artificial","tag-itenaccion","tag-purga-studio"],"_links":{"self":[{"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/posts\/187657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/comments?post=187657"}],"version-history":[{"count":0,"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/posts\/187657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/media\/187658"}],"wp:attachment":[{"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/media?parent=187657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/categories?post=187657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itsitio.com\/ar\/wp-json\/wp\/v2\/tags?post=187657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}